<div id="error"><p class="wpdberror"><strong>WordPress database error:</strong> [Deadlock found when trying to get lock; try restarting transaction]<br /><code>UPDATE `apswp_options` SET `option_value` = &#039;a:2:{s:21:\&quot;id_slug_type_path_map\&quot;;a:1:{i:7180;a:3:{s:4:\&quot;slug\&quot;;s:19:\&quot;shortcodes-ultimate\&quot;;s:4:\&quot;type\&quot;;s:6:\&quot;plugin\&quot;;s:4:\&quot;path\&quot;;s:43:\&quot;shortcodes-ultimate/shortcodes-ultimate.php\&quot;;}}s:11:\&quot;plugin_data\&quot;;a:1:{s:19:\&quot;shortcodes-ultimate\&quot;;a:1:{s:16:\&quot;plugin_main_file\&quot;;O:8:\&quot;stdClass\&quot;:1:{s:4:\&quot;path\&quot;;s:43:\&quot;shortcodes-ultimate/shortcodes-ultimate.php\&quot;;}}}}&#039; WHERE `option_name` = &#039;fs_accounts&#039;</code></p></div>{"id":4399,"date":"2016-07-13T12:49:08","date_gmt":"2016-07-13T12:49:08","guid":{"rendered":"http:\/\/infantv.com.br\/infantv\/?p=4399"},"modified":"2016-07-14T11:57:58","modified_gmt":"2016-07-14T11:57:58","slug":"roger-ramjet-roger-ramjet-1965-elenco","status":"publish","type":"post","link":"https:\/\/infantv.com.br\/infantv\/roger-ramjet-roger-ramjet-1965-elenco\/","title":{"rendered":"Roger Ramjet (Roger Ramjet  -1965) &#8211; Elenco"},"content":{"rendered":"<div style=\"text-align:center\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet5.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet5.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet5.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet5.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet5.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet5.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet5.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet5.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet5.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet5.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet5.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" width=\"331\" height=\"236\" fifu-data-src=\"https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet5.jpg?ssl=1\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Roger Ramjet (Roger Ramjet  -1965) \u2013 Elenco\" title=\"Roger Ramjet (Roger Ramjet  -1965) \u2013 Elenco\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet5.jpg?ssl=1 331w, https:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet5-300x214.jpg 300w\" sizes=\"(max-width: 331px) 100vw, 331px\" \/><\/div><p style=\"text-align: center;\"><a href=\"http:\/\/infantv.com.br\/infantv\/?p=4375\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_logo-300x225.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_logo-300x225.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_logo-300x225.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_logo-300x225.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_logo-300x225.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_logo-300x225.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_logo-300x225.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_logo-300x225.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_logo-300x225.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_logo-300x225.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_logo-300x225.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-4378 size-medium\" style=\"border-radius: 20px;\" fifu-data-src=\"https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_logo-300x225.jpg?ssl=1\" alt=\"\" width=\"300\" height=\"225\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><strong>Est\u00fadio de dublagem:<\/strong>\u00a0Cinecastro<\/p>\n<table id=\"AutoNumber11\" style=\"border-width: 0;\" border=\"0\" width=\"90%\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" bgcolor=\"#C0C0C0\" width=\"33%\" height=\"1\"><b> PERSONAGEM<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" bgcolor=\"#C0C0C0\" width=\"33%\" height=\"1\"><b> DUBLAGEM<\/b><b> ORIGINAL<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" bgcolor=\"#C0C0C0\" width=\"34%\" height=\"1\"><b> DUBLAGEM<\/b><b> BRASILEIRA<\/b><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"101\"><a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet4.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet4.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet4.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet4.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet4.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet4.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet4.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet4.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet4.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet4.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet4.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet4.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-4400\" fifu-data-src=\"https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet4.jpg?ssl=1\" alt=\"\" width=\"90\" height=\"101\" \/><\/a><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"101\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/garyowens.gif?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/garyowens.gif?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/garyowens.gif?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/garyowens.gif?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/garyowens.gif?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/garyowens.gif?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/garyowens.gif?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/garyowens.gif?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/garyowens.gif?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/garyowens.gif?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/garyowens.gif?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone\" fifu-data-src=\"https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/garyowens.gif?ssl=1\" alt=\"\" width=\"96\" height=\"101\" \/><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"101\"><a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/ribeirosantos.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/ribeirosantos.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/ribeirosantos.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/ribeirosantos.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/ribeirosantos.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/ribeirosantos.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/ribeirosantos.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/ribeirosantos.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/ribeirosantos.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/ribeirosantos.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/ribeirosantos.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/ribeirosantos.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-4410\" fifu-data-src=\"https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/ribeirosantos.jpg?ssl=1\" alt=\"\" width=\"90\" height=\"101\" \/><\/a><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>Roger Ramjet<br \/>\n<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>Gary Owens<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"1\"><b>Ribeiro Santos<\/b><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" colspan=\"3\" align=\"center\" valign=\"top\" width=\"100%\" height=\"1\">\n<hr size=\"1\" \/>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"101\"><a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_yank.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_yank.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_yank.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_yank.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_yank.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_yank.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_yank.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_yank.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_yank.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_yank.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_yank.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_yank.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-4409\" fifu-data-src=\"https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_yank.jpg?ssl=1\" alt=\"\" width=\"90\" height=\"101\" \/><\/a><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"101\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i1.wp.com\/infantv.com.br\/infantv\/dicionario\/dickbeals.gif?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/dicionario\/dickbeals.gif?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/dicionario\/dickbeals.gif?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/dicionario\/dickbeals.gif?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/dicionario\/dickbeals.gif?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/dicionario\/dickbeals.gif?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/dicionario\/dickbeals.gif?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/dicionario\/dickbeals.gif?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/dicionario\/dickbeals.gif?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/dicionario\/dickbeals.gif?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/dicionario\/dickbeals.gif?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone\" fifu-data-src=\"https:\/\/i1.wp.com\/infantv.com.br\/infantv\/dicionario\/dickbeals.gif?ssl=1\" alt=\"\" width=\"96\" height=\"101\" \/><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"101\"><a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/glorialadany.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/glorialadany.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/glorialadany.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/glorialadany.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/glorialadany.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/glorialadany.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/glorialadany.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/glorialadany.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/glorialadany.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/glorialadany.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/glorialadany.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/glorialadany.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-1264\" fifu-data-src=\"https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/glorialadany.jpg?ssl=1\" alt=\"\" width=\"90\" height=\"101\" \/><\/a><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>Yank<br \/>\n<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>Dick Beals<br \/>\n<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"1\"><b>Gl\u00f3ria Ladany<br \/>\n<\/b><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" colspan=\"3\" align=\"center\" valign=\"top\" width=\"100%\" height=\"1\">\n<hr size=\"1\" \/>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"101\"><a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_doodle.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_doodle.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_doodle.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_doodle.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_doodle.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_doodle.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_doodle.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_doodle.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_doodle.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_doodle.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_doodle.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_doodle.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-4403\" fifu-data-src=\"https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_doodle.jpg?ssl=1\" alt=\"\" width=\"90\" height=\"101\" \/><\/a><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"101\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/genemoss.gif?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/genemoss.gif?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/genemoss.gif?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/genemoss.gif?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/genemoss.gif?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/genemoss.gif?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/genemoss.gif?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/genemoss.gif?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/genemoss.gif?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/genemoss.gif?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/genemoss.gif?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone\" fifu-data-src=\"https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/genemoss.gif?ssl=1\" alt=\"\" width=\"96\" height=\"101\" \/><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"101\"><a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/luizmanoel.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/luizmanoel.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/luizmanoel.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/luizmanoel.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/luizmanoel.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/luizmanoel.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/luizmanoel.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/luizmanoel.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/luizmanoel.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/luizmanoel.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/luizmanoel.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/luizmanoel.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-1415\" fifu-data-src=\"https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/luizmanoel.jpg?ssl=1\" alt=\"\" width=\"90\" height=\"101\" \/><\/a><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>Doodle<br \/>\n<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>Gene Moss<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"1\"><b>Luiz Manoel<\/b><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" colspan=\"3\" align=\"center\" valign=\"top\" width=\"100%\" height=\"1\">\n<hr size=\"1\" \/>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"101\"><a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_dee.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_dee.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_dee.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_dee.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_dee.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_dee.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_dee.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_dee.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_dee.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_dee.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_dee.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_dee.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-4402\" fifu-data-src=\"https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_dee.jpg?ssl=1\" alt=\"\" width=\"90\" height=\"101\" \/><\/a><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"101\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i1.wp.com\/infantv.com.br\/infantv\/dicionario\/joangerber.gif?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/dicionario\/joangerber.gif?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/dicionario\/joangerber.gif?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/dicionario\/joangerber.gif?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/dicionario\/joangerber.gif?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/dicionario\/joangerber.gif?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/dicionario\/joangerber.gif?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/dicionario\/joangerber.gif?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/dicionario\/joangerber.gif?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/dicionario\/joangerber.gif?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/dicionario\/joangerber.gif?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone\" fifu-data-src=\"https:\/\/i1.wp.com\/infantv.com.br\/infantv\/dicionario\/joangerber.gif?ssl=1\" alt=\"\" width=\"96\" height=\"101\" \/><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"101\"><a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/ruthschelske.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/ruthschelske.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/ruthschelske.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/ruthschelske.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/ruthschelske.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/ruthschelske.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/ruthschelske.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/ruthschelske.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/ruthschelske.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/ruthschelske.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/ruthschelske.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/ruthschelske.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-1470\" fifu-data-src=\"https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/ruthschelske.jpg?ssl=1\" alt=\"\" width=\"90\" height=\"101\" \/><\/a><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>Dee<br \/>\n<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>Joan Gerber<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"1\"><b>Ruth Schelske<\/b><em><b><br \/>\n<\/b><\/em><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" colspan=\"3\" align=\"center\" valign=\"top\" width=\"100%\" height=\"1\">\n<hr size=\"1\" \/>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"101\">\u00a0<a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_dan.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_dan.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_dan.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_dan.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_dan.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_dan.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_dan.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_dan.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_dan.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_dan.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_dan.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_dan.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-4401\" fifu-data-src=\"https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_dan.jpg?ssl=1\" alt=\"rogerramjet_dan\" width=\"90\" height=\"101\" \/><\/a><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"101\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i1.wp.com\/infantv.com.br\/infantv\/dicionario\/dickbeals.gif?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/dicionario\/dickbeals.gif?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/dicionario\/dickbeals.gif?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/dicionario\/dickbeals.gif?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/dicionario\/dickbeals.gif?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/dicionario\/dickbeals.gif?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/dicionario\/dickbeals.gif?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/dicionario\/dickbeals.gif?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/dicionario\/dickbeals.gif?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/dicionario\/dickbeals.gif?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/dicionario\/dickbeals.gif?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone\" fifu-data-src=\"https:\/\/i1.wp.com\/infantv.com.br\/infantv\/dicionario\/dickbeals.gif?ssl=1\" alt=\"\" width=\"96\" height=\"101\" \/><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"101\"><a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/angelabonatti.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/angelabonatti.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/angelabonatti.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/angelabonatti.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/angelabonatti.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/angelabonatti.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/angelabonatti.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/angelabonatti.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/angelabonatti.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/angelabonatti.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/angelabonatti.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/angelabonatti.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-570\" fifu-data-src=\"https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/angelabonatti.jpg?ssl=1\" alt=\"\" width=\"90\" height=\"101\" \/><\/a><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>Dan<br \/>\n<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>Dick Beals<br \/>\n<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"1\"><b>\u00c2ngela\u00a0Bonatti<\/b><em><b><br \/>\n<\/b><\/em><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" colspan=\"3\" align=\"center\" valign=\"top\" width=\"100%\" height=\"1\">\n<hr size=\"1\" \/>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"101\"><a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_lottlalove.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_lottlalove.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_lottlalove.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_lottlalove.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_lottlalove.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_lottlalove.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_lottlalove.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_lottlalove.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_lottlalove.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_lottlalove.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_lottlalove.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_lottlalove.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-4406\" fifu-data-src=\"https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_lottlalove.jpg?ssl=1\" alt=\"\" width=\"90\" height=\"101\" \/><\/a><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"101\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i1.wp.com\/infantv.com.br\/infantv\/dicionario\/joangerber.gif?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/dicionario\/joangerber.gif?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/dicionario\/joangerber.gif?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/dicionario\/joangerber.gif?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/dicionario\/joangerber.gif?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/dicionario\/joangerber.gif?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/dicionario\/joangerber.gif?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/dicionario\/joangerber.gif?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/dicionario\/joangerber.gif?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/dicionario\/joangerber.gif?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/dicionario\/joangerber.gif?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone\" fifu-data-src=\"https:\/\/i1.wp.com\/infantv.com.br\/infantv\/dicionario\/joangerber.gif?ssl=1\" alt=\"\" width=\"96\" height=\"101\" \/><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"101\"><a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/nairamorim.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/nairamorim.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/nairamorim.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/nairamorim.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/nairamorim.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/nairamorim.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/nairamorim.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/nairamorim.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/nairamorim.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/nairamorim.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/nairamorim.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/nairamorim.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-735\" fifu-data-src=\"https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/nairamorim.jpg?ssl=1\" alt=\"\" width=\"90\" height=\"101\" \/><\/a><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>Lotta Love<br \/>\n<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>Joan Gerber<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"1\"><b>Nair Amorim<\/b><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" colspan=\"3\" align=\"center\" valign=\"top\" width=\"100%\" height=\"1\">\n<hr size=\"1\" \/>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"101\"><a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_maramget.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_maramget.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_maramget.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_maramget.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_maramget.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_maramget.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_maramget.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_maramget.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_maramget.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_maramget.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_maramget.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_maramget.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-4407\" fifu-data-src=\"https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_maramget.jpg?ssl=1\" alt=\"\" width=\"90\" height=\"101\" \/><\/a><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"101\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/bobarbogast.gif?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/bobarbogast.gif?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/bobarbogast.gif?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/bobarbogast.gif?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/bobarbogast.gif?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/bobarbogast.gif?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/bobarbogast.gif?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/bobarbogast.gif?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/bobarbogast.gif?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/bobarbogast.gif?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/bobarbogast.gif?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone\" fifu-data-src=\"https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/bobarbogast.gif?ssl=1\" alt=\"\" width=\"96\" height=\"101\" \/><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"101\"><a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/soniademoraes.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/soniademoraes.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/soniademoraes.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/soniademoraes.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/soniademoraes.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/soniademoraes.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/soniademoraes.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/soniademoraes.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/soniademoraes.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/soniademoraes.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/soniademoraes.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/soniademoraes.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-4411\" fifu-data-src=\"https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/soniademoraes.jpg?ssl=1\" alt=\"\" width=\"90\" height=\"101\" \/><\/a><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>Ma Ramjet<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>Bob Arbogast<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"1\"><b>S\u00f4nia de Moraes<\/b><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" colspan=\"3\" align=\"center\" valign=\"top\" width=\"100%\" height=\"1\">\n<hr size=\"1\" \/>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"101\"><a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_noodle.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_noodle.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_noodle.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_noodle.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_noodle.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_noodle.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_noodle.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_noodle.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_noodle.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_noodle.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_noodle.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_noodle.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-4408\" fifu-data-src=\"https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_noodle.jpg?ssl=1\" alt=\"\" width=\"90\" height=\"101\" \/><\/a><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"101\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/genemoss.gif?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/genemoss.gif?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/genemoss.gif?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/genemoss.gif?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/genemoss.gif?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/genemoss.gif?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/genemoss.gif?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/genemoss.gif?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/genemoss.gif?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/genemoss.gif?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/genemoss.gif?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone\" fifu-data-src=\"https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/genemoss.gif?ssl=1\" alt=\"\" width=\"96\" height=\"101\" \/><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"101\"><a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/miltonrangel.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/miltonrangel.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/miltonrangel.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/miltonrangel.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/miltonrangel.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/miltonrangel.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/miltonrangel.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/miltonrangel.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/miltonrangel.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/miltonrangel.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/miltonrangel.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/miltonrangel.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-2977\" fifu-data-src=\"https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/miltonrangel.jpg?ssl=1\" alt=\"\" width=\"90\" height=\"101\" \/><\/a><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>Noodle<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>Gene Moss<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"1\"><b>Milton Rangel<\/b><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" colspan=\"3\" align=\"center\" valign=\"top\" width=\"100%\" height=\"1\">\n<hr size=\"1\" \/>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"101\">\u00a0<a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_gi.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_gi.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_gi.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_gi.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_gi.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_gi.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_gi.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_gi.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_gi.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_gi.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_gi.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_gi.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-4404\" fifu-data-src=\"https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_gi.jpg?ssl=1\" alt=\"rogerramjet_gi\" width=\"90\" height=\"101\" \/><\/a><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"101\">\u00a0<img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/bobarbogast.gif?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/bobarbogast.gif?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/bobarbogast.gif?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/bobarbogast.gif?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/bobarbogast.gif?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/bobarbogast.gif?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/bobarbogast.gif?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/bobarbogast.gif?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/bobarbogast.gif?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/bobarbogast.gif?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/bobarbogast.gif?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone\" fifu-data-src=\"https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/bobarbogast.gif?ssl=1\" alt=\"\" width=\"96\" height=\"101\" \/><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"101\"><a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/jomerypozzoli.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/jomerypozzoli.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/jomerypozzoli.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/jomerypozzoli.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/jomerypozzoli.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/jomerypozzoli.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/jomerypozzoli.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/jomerypozzoli.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/jomerypozzoli.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/jomerypozzoli.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/jomerypozzoli.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/jomerypozzoli.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-2234\" fifu-data-src=\"https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/jomerypozzoli.jpg?ssl=1\" alt=\"\" width=\"90\" height=\"101\" \/><\/a><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>General GI<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\">\u00a0<b>Bob Arbogast<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"1\"><b>Jomery Pozzoli<\/b><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" colspan=\"3\" align=\"center\" valign=\"top\" width=\"100%\" height=\"1\">\n<hr size=\"1\" \/>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"101\"><a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_lance.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_lance.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_lance.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_lance.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_lance.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_lance.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_lance.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_lance.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_lance.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_lance.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_lance.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_lance.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-4405\" fifu-data-src=\"https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/rogerramjet_lance.jpg?ssl=1\" alt=\"\" width=\"90\" height=\"101\" \/><\/a><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"101\"><a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/semi.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/semi.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/semi.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/semi.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/semi.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/semi.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/semi.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/semi.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/semi.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/semi.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/semi.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/semi.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-265\" fifu-data-src=\"https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/semi.jpg?ssl=1\" alt=\"semi\" width=\"90\" height=\"101\" \/><\/a><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"101\"><a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/domiciocosta.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/domiciocosta.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/domiciocosta.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/domiciocosta.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/domiciocosta.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/domiciocosta.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/domiciocosta.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/domiciocosta.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/domiciocosta.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/domiciocosta.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/domiciocosta.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/domiciocosta.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-744\" fifu-data-src=\"https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/domiciocosta.jpg?ssl=1\" alt=\"\" width=\"90\" height=\"101\" \/><\/a><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>Lance<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>Paul Shively<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"1\"><b>Dom\u00edcio Costa<\/b><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" colspan=\"3\" align=\"center\" valign=\"top\" width=\"100%\" height=\"1\">\n<hr size=\"1\" \/>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"101\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/narrador.gif?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/narrador.gif?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/narrador.gif?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/narrador.gif?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/narrador.gif?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/narrador.gif?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/narrador.gif?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/narrador.gif?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/narrador.gif?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/narrador.gif?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/narrador.gif?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone\" fifu-data-src=\"https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/narrador.gif?ssl=1\" alt=\"\" width=\"96\" height=\"101\" \/><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"101\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/davidketchum.gif?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/davidketchum.gif?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/davidketchum.gif?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/davidketchum.gif?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/davidketchum.gif?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/davidketchum.gif?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/davidketchum.gif?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/davidketchum.gif?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/davidketchum.gif?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/davidketchum.gif?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/davidketchum.gif?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone\" fifu-data-src=\"https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/davidketchum.gif?ssl=1\" alt=\"\" width=\"96\" height=\"101\" \/><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"101\"><a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/miltonrangel.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/miltonrangel.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/miltonrangel.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/miltonrangel.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/miltonrangel.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/miltonrangel.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/miltonrangel.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/miltonrangel.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/miltonrangel.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/miltonrangel.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/miltonrangel.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/miltonrangel.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-2977\" fifu-data-src=\"https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/miltonrangel.jpg?ssl=1\" alt=\"\" width=\"90\" height=\"101\" \/><\/a><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>Narrador<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>David Ketchum<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"1\"><b>Milton Rangel<\/b><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" colspan=\"3\" align=\"center\" valign=\"top\" width=\"100%\" height=\"1\">\n<hr size=\"1\" \/>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Est\u00fadio de dublagem:\u00a0Cinecastro PERSONAGEM DUBLAGEM ORIGINAL DUBLAGEM BRASILEIRA Roger Ramjet Gary Owens Ribeiro Santos Yank Dick Beals Gl\u00f3ria Ladany Doodle Gene Moss Luiz Manoel Dee Joan Gerber Ruth Schelske \u00a0 Dan Dick Beals \u00c2ngela\u00a0Bonatti Lotta Love Joan Gerber Nair Amorim Ma Ramjet Bob Arbogast S\u00f4nia de Moraes Noodle Gene Moss Milton Rangel \u00a0 \u00a0 General [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4382,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","fifu_image_url":"","fifu_image_alt":""},"categories":[20],"tags":[],"_links":{"self":[{"href":"https:\/\/infantv.com.br\/infantv\/wp-json\/wp\/v2\/posts\/4399"}],"collection":[{"href":"https:\/\/infantv.com.br\/infantv\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infantv.com.br\/infantv\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infantv.com.br\/infantv\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/infantv.com.br\/infantv\/wp-json\/wp\/v2\/comments?post=4399"}],"version-history":[{"count":2,"href":"https:\/\/infantv.com.br\/infantv\/wp-json\/wp\/v2\/posts\/4399\/revisions"}],"predecessor-version":[{"id":4652,"href":"https:\/\/infantv.com.br\/infantv\/wp-json\/wp\/v2\/posts\/4399\/revisions\/4652"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infantv.com.br\/infantv\/wp-json\/wp\/v2\/media\/4382"}],"wp:attachment":[{"href":"https:\/\/infantv.com.br\/infantv\/wp-json\/wp\/v2\/media?parent=4399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infantv.com.br\/infantv\/wp-json\/wp\/v2\/categories?post=4399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infantv.com.br\/infantv\/wp-json\/wp\/v2\/tags?post=4399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}