<div id="error"><p class="wpdberror"><strong>WordPress database error:</strong> [Deadlock found when trying to get lock; try restarting transaction]<br /><code>UPDATE `apswp_options` SET `option_value` = &#039;a:3:{s:21:\&quot;id_slug_type_path_map\&quot;;a:1:{i:7180;a:3:{s:4:\&quot;slug\&quot;;s:19:\&quot;shortcodes-ultimate\&quot;;s:4:\&quot;type\&quot;;s:6:\&quot;plugin\&quot;;s:4:\&quot;path\&quot;;s:43:\&quot;shortcodes-ultimate/shortcodes-ultimate.php\&quot;;}}s:11:\&quot;plugin_data\&quot;;a:1:{s:19:\&quot;shortcodes-ultimate\&quot;;a:11:{s:16:\&quot;plugin_main_file\&quot;;O:8:\&quot;stdClass\&quot;:1:{s:4:\&quot;path\&quot;;s:43:\&quot;shortcodes-ultimate/shortcodes-ultimate.php\&quot;;}s:20:\&quot;is_network_activated\&quot;;b:0;s:17:\&quot;install_timestamp\&quot;;i:1778683965;s:16:\&quot;sdk_last_version\&quot;;N;s:11:\&quot;sdk_version\&quot;;s:5:\&quot;2.5.7\&quot;;s:16:\&quot;sdk_upgrade_mode\&quot;;b:1;s:18:\&quot;sdk_downgrade_mode\&quot;;b:0;s:19:\&quot;plugin_last_version\&quot;;N;s:14:\&quot;plugin_version\&quot;;s:6:\&quot;5.13.0\&quot;;s:19:\&quot;plugin_upgrade_mode\&quot;;b:1;s:21:\&quot;plugin_downgrade_mode\&quot;;b:0;}}s:13:\&quot;file_slug_map\&quot;;a:1:{s:43:\&quot;shortcodes-ultimate/shortcodes-ultimate.php\&quot;;s:19:\&quot;shortcodes-ultimate\&quot;;}}&#039; WHERE `option_name` = &#039;fs_accounts&#039;</code></p></div>{"id":2442,"date":"2016-07-03T16:15:06","date_gmt":"2016-07-03T16:15:06","guid":{"rendered":"http:\/\/infantv.com.br\/infantv\/?p=2442"},"modified":"2016-07-09T22:58:46","modified_gmt":"2016-07-09T22:58:46","slug":"familia-dracula-drak-pack-1980-elenco","status":"publish","type":"post","link":"https:\/\/infantv.com.br\/infantv\/familia-dracula-drak-pack-1980-elenco\/","title":{"rendered":"Fam\u00edlia Dr\u00e1cula (Drak Pack &#8211; 1980) &#8211; Elenco"},"content":{"rendered":"<div style=\"text-align:center\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_dracjunior.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_dracjunior.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_dracjunior.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_dracjunior.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_dracjunior.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_dracjunior.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_dracjunior.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_dracjunior.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_dracjunior.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_dracjunior.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_dracjunior.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" width=\"210\" height=\"240\" fifu-data-src=\"https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_dracjunior.jpg?ssl=1\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Fam\u00edlia Dr\u00e1cula (Drak Pack \u2013 1980) \u2013 Elenco\" title=\"Fam\u00edlia Dr\u00e1cula (Drak Pack \u2013 1980) \u2013 Elenco\" decoding=\"async\" loading=\"lazy\" \/><\/div><p style=\"text-align: center;\"><a href=\"http:\/\/infantv.com.br\/infantv\/?p=2423\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula-300x229.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula-300x229.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula-300x229.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula-300x229.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula-300x229.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula-300x229.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula-300x229.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula-300x229.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula-300x229.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula-300x229.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula-300x229.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-2425 size-medium\" style=\"border-radius: 20px;\" fifu-data-src=\"https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula-300x229.jpg?ssl=1\" alt=\"\" width=\"300\" height=\"229\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><strong>Est\u00fadio de dublagem:<\/strong> \u00c1lamo<\/p>\n<p style=\"text-align: center;\"><strong>Est\u00fadio de redublagem:<\/strong>\u00a0 Herbert Richers<\/p>\n<p style=\"text-align: left;\">[su_tabs][su_tab title=&#8221;\u00c1lamo&#8221;]<\/p>\n<table id=\"AutoNumber11\" style=\"border-width: 0;\" border=\"0\" width=\"90%\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" bgcolor=\"#C0C0C0\" width=\"33%\" height=\"1\"><b> PERSONAGEM<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" bgcolor=\"#C0C0C0\" width=\"33%\" height=\"1\"><b> DUBLAGEM<\/b><b> ORIGINAL<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" bgcolor=\"#C0C0C0\" width=\"34%\" height=\"1\"><b> DUBLAGEM<\/b><b> BRASILEIRA<\/b><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"109\"><a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_dracjunior.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_dracjunior.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_dracjunior.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_dracjunior.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_dracjunior.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_dracjunior.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_dracjunior.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_dracjunior.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_dracjunior.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_dracjunior.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_dracjunior.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_dracjunior.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-2443\" fifu-data-src=\"https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_dracjunior.jpg?ssl=1\" alt=\"\" width=\"90\" height=\"103\" \/><\/a><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"109\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i3.wp.com\/infantv.com.br\/infantv\/dicionario\/jerrydexter.gif?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/dicionario\/jerrydexter.gif?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/dicionario\/jerrydexter.gif?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/dicionario\/jerrydexter.gif?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/dicionario\/jerrydexter.gif?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/dicionario\/jerrydexter.gif?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/dicionario\/jerrydexter.gif?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/dicionario\/jerrydexter.gif?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/dicionario\/jerrydexter.gif?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/dicionario\/jerrydexter.gif?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/dicionario\/jerrydexter.gif?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone\" fifu-data-src=\"https:\/\/i3.wp.com\/infantv.com.br\/infantv\/dicionario\/jerrydexter.gif?ssl=1\" alt=\"\" width=\"96\" height=\"110\" \/><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"109\">\u00a0<a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/renatomarcio.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/renatomarcio.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/renatomarcio.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/renatomarcio.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/renatomarcio.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/renatomarcio.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/renatomarcio.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/renatomarcio.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/renatomarcio.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/renatomarcio.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/renatomarcio.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/renatomarcio.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-2452\" fifu-data-src=\"https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/renatomarcio.jpg?ssl=1\" alt=\"renatomarcio\" width=\"90\" height=\"103\" \/><\/a><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>Drac J\u00fanior<br \/>\n<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>Jerry Dexter<br \/>\n<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"1\"><b>Renato M\u00e1rcio<\/b><em><b><br \/>\n<\/b><\/em><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" colspan=\"3\" align=\"center\" valign=\"top\" width=\"100%\" height=\"1\">\n<hr size=\"1\" \/>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"101\"><a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_lobao.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_lobao.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_lobao.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_lobao.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_lobao.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_lobao.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_lobao.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_lobao.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_lobao.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_lobao.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_lobao.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_lobao.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-2447\" fifu-data-src=\"https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_lobao.jpg?ssl=1\" alt=\"\" width=\"90\" height=\"103\" \/><\/a><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"101\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/williamcallaway.gif?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/williamcallaway.gif?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/williamcallaway.gif?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/williamcallaway.gif?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/williamcallaway.gif?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/williamcallaway.gif?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/williamcallaway.gif?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/williamcallaway.gif?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/williamcallaway.gif?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/williamcallaway.gif?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/williamcallaway.gif?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone\" fifu-data-src=\"https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/williamcallaway.gif?ssl=1\" alt=\"\" width=\"96\" height=\"110\" \/><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"101\"><a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/nelsonmachado.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/nelsonmachado.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/nelsonmachado.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/nelsonmachado.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/nelsonmachado.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/nelsonmachado.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/nelsonmachado.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/nelsonmachado.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/nelsonmachado.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/nelsonmachado.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/nelsonmachado.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/nelsonmachado.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-2453\" fifu-data-src=\"https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/nelsonmachado.jpg?ssl=1\" alt=\"\" width=\"90\" height=\"103\" \/><\/a><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>Lob\u00e3o<br \/>\n<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>William Callaway<br \/>\n<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"1\"><b>Nelson Machado<br \/>\n<\/b><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" colspan=\"3\" align=\"center\" valign=\"top\" width=\"100%\" height=\"1\">\n<hr size=\"1\" \/>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"118\"><a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_frankie.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_frankie.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_frankie.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_frankie.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_frankie.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_frankie.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_frankie.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_frankie.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_frankie.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_frankie.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_frankie.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_frankie.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-2445\" fifu-data-src=\"https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_frankie.jpg?ssl=1\" alt=\"\" width=\"90\" height=\"103\" \/><\/a><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"118\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/williamcallaway.gif?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/williamcallaway.gif?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/williamcallaway.gif?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/williamcallaway.gif?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/williamcallaway.gif?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/williamcallaway.gif?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/williamcallaway.gif?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/williamcallaway.gif?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/williamcallaway.gif?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/williamcallaway.gif?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/williamcallaway.gif?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone\" fifu-data-src=\"https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/williamcallaway.gif?ssl=1\" alt=\"\" width=\"96\" height=\"110\" \/><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"118\"><a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/carlosguerra.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/carlosguerra.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/carlosguerra.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/carlosguerra.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/carlosguerra.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/carlosguerra.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/carlosguerra.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/carlosguerra.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/carlosguerra.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/carlosguerra.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/carlosguerra.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/carlosguerra.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-1095\" fifu-data-src=\"https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/carlosguerra.jpg?ssl=1\" alt=\"\" width=\"90\" height=\"103\" \/><\/a><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>Frankie<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>William Callaway<br \/>\n<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"1\"><b>Jos\u00e9 Carlos Guerra<\/b><em><b><br \/>\n<\/b><\/em><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" colspan=\"3\" align=\"center\" valign=\"top\" width=\"100%\" height=\"1\">\n<hr size=\"1\" \/>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"109\"><a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_granded.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_granded.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_granded.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_granded.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_granded.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_granded.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_granded.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_granded.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_granded.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_granded.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_granded.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_granded.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-2446\" fifu-data-src=\"https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_granded.jpg?ssl=1\" alt=\"\" width=\"90\" height=\"103\" \/><\/a><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"109\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/alanoppenheimer.gif?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/alanoppenheimer.gif?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/alanoppenheimer.gif?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/alanoppenheimer.gif?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/alanoppenheimer.gif?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/alanoppenheimer.gif?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/alanoppenheimer.gif?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/alanoppenheimer.gif?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/alanoppenheimer.gif?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/alanoppenheimer.gif?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/alanoppenheimer.gif?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone\" fifu-data-src=\"https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/alanoppenheimer.gif?ssl=1\" alt=\"\" width=\"96\" height=\"110\" \/><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"109\"><a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/gastaomalta.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/gastaomalta.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/gastaomalta.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/gastaomalta.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/gastaomalta.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/gastaomalta.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/gastaomalta.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/gastaomalta.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/gastaomalta.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/gastaomalta.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/gastaomalta.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/gastaomalta.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-2454\" fifu-data-src=\"https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/gastaomalta.jpg?ssl=1\" alt=\"\" width=\"90\" height=\"103\" \/><\/a><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>Dracul\u00e3o<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>Alan Oppenheimer<br \/>\n<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"1\"><b>Gast\u00e3o Malta<\/b><em><b><br \/>\n<\/b><\/em><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" colspan=\"3\" align=\"center\" valign=\"top\" width=\"100%\" height=\"1\">\n<hr size=\"1\" \/>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"109\"><a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_drterror.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_drterror.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_drterror.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_drterror.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_drterror.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_drterror.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_drterror.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_drterror.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_drterror.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_drterror.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_drterror.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_drterror.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-2444\" fifu-data-src=\"https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_drterror.jpg?ssl=1\" alt=\"\" width=\"90\" height=\"103\" \/><\/a><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"109\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/hansconried.gif?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/hansconried.gif?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/hansconried.gif?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/hansconried.gif?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/hansconried.gif?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/hansconried.gif?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/hansconried.gif?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/hansconried.gif?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/hansconried.gif?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/hansconried.gif?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/hansconried.gif?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone\" fifu-data-src=\"https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/hansconried.gif?ssl=1\" alt=\"\" width=\"96\" height=\"110\" \/><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"109\"><a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/mariojorgemontini.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/mariojorgemontini.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/mariojorgemontini.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/mariojorgemontini.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/mariojorgemontini.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/mariojorgemontini.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/mariojorgemontini.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/mariojorgemontini.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/mariojorgemontini.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/mariojorgemontini.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/mariojorgemontini.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/mariojorgemontini.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-1988\" fifu-data-src=\"https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/mariojorgemontini.jpg?ssl=1\" alt=\"\" width=\"90\" height=\"103\" \/><\/a><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>Dr. Terror<br \/>\n<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>Hans Conried<br \/>\n<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"1\"><b>M\u00e1rio Jorge Montini<\/b><em><b><br \/>\n<\/b><\/em><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" colspan=\"3\" align=\"center\" valign=\"top\" width=\"100%\" height=\"1\">\n<hr size=\"1\" \/>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"109\"><a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_sapao.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_sapao.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_sapao.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_sapao.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_sapao.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_sapao.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_sapao.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_sapao.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_sapao.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_sapao.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_sapao.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_sapao.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-2450\" fifu-data-src=\"https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_sapao.jpg?ssl=1\" alt=\"\" width=\"90\" height=\"103\" \/><\/a><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"109\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i1.wp.com\/www.infantv.com.br\/infantv\/dicionario\/donmessik.gif?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i1.wp.com\/www.infantv.com.br\/infantv\/dicionario\/donmessik.gif?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i1.wp.com\/www.infantv.com.br\/infantv\/dicionario\/donmessik.gif?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i1.wp.com\/www.infantv.com.br\/infantv\/dicionario\/donmessik.gif?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i1.wp.com\/www.infantv.com.br\/infantv\/dicionario\/donmessik.gif?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i1.wp.com\/www.infantv.com.br\/infantv\/dicionario\/donmessik.gif?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i1.wp.com\/www.infantv.com.br\/infantv\/dicionario\/donmessik.gif?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i1.wp.com\/www.infantv.com.br\/infantv\/dicionario\/donmessik.gif?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i1.wp.com\/www.infantv.com.br\/infantv\/dicionario\/donmessik.gif?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i1.wp.com\/www.infantv.com.br\/infantv\/dicionario\/donmessik.gif?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i1.wp.com\/www.infantv.com.br\/infantv\/dicionario\/donmessik.gif?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone\" fifu-data-src=\"https:\/\/i1.wp.com\/www.infantv.com.br\/infantv\/dicionario\/donmessik.gif?ssl=1\" alt=\"\" width=\"96\" height=\"110\" \/><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"109\"><a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/maurodealmeida.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/maurodealmeida.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/maurodealmeida.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/maurodealmeida.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/maurodealmeida.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/maurodealmeida.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/maurodealmeida.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/maurodealmeida.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/maurodealmeida.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/maurodealmeida.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/maurodealmeida.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/maurodealmeida.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-2455\" fifu-data-src=\"https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/maurodealmeida.jpg?ssl=1\" alt=\"\" width=\"90\" height=\"103\" \/><\/a><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>Sap\u00e3o<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>Don Messick<br \/>\n<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"1\"><b>Mauro de Almeida<\/b><em><b><br \/>\n<\/b><\/em><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" colspan=\"3\" align=\"center\" valign=\"top\" width=\"100%\" height=\"1\">\n<hr size=\"1\" \/>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"109\"><a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_vampira.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_vampira.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_vampira.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_vampira.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_vampira.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_vampira.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_vampira.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_vampira.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_vampira.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_vampira.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_vampira.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_vampira.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-2451\" fifu-data-src=\"https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_vampira.jpg?ssl=1\" alt=\"\" width=\"90\" height=\"103\" \/><\/a><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"109\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i3.wp.com\/infantv.com.br\/infantv\/dicionario\/juliemac.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/dicionario\/juliemac.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/dicionario\/juliemac.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/dicionario\/juliemac.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/dicionario\/juliemac.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/dicionario\/juliemac.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/dicionario\/juliemac.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/dicionario\/juliemac.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/dicionario\/juliemac.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/dicionario\/juliemac.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/dicionario\/juliemac.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone\" fifu-data-src=\"https:\/\/i3.wp.com\/infantv.com.br\/infantv\/dicionario\/juliemac.jpg?ssl=1\" alt=\"\" width=\"96\" height=\"110\" \/><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"109\"><a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/nairsilva.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/nairsilva.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/nairsilva.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/nairsilva.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/nairsilva.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/nairsilva.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/nairsilva.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/nairsilva.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/nairsilva.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/nairsilva.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/nairsilva.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/nairsilva.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-1143\" fifu-data-src=\"https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/nairsilva.jpg?ssl=1\" alt=\"\" width=\"90\" height=\"103\" \/><\/a><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>Vampira<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>Julie McWhirter<br \/>\n<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"1\"><b>Nair Silva<\/b><em><b><br \/>\n<\/b><\/em><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" colspan=\"3\" align=\"center\" valign=\"top\" width=\"100%\" height=\"1\">\n<hr size=\"1\" \/>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"109\"><a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_mumia.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_mumia.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_mumia.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_mumia.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_mumia.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_mumia.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_mumia.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_mumia.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_mumia.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_mumia.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_mumia.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_mumia.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-2449\" fifu-data-src=\"https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_mumia.jpg?ssl=1\" alt=\"\" width=\"90\" height=\"103\" \/><\/a><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"109\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/chuckmccann.gif?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/chuckmccann.gif?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/chuckmccann.gif?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/chuckmccann.gif?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/chuckmccann.gif?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/chuckmccann.gif?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/chuckmccann.gif?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/chuckmccann.gif?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/chuckmccann.gif?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/chuckmccann.gif?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/chuckmccann.gif?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone\" fifu-data-src=\"https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/chuckmccann.gif?ssl=1\" alt=\"\" width=\"96\" height=\"110\" \/><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"109\"><a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/arakensaldanha.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/arakensaldanha.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/arakensaldanha.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/arakensaldanha.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/arakensaldanha.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/arakensaldanha.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/arakensaldanha.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/arakensaldanha.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/arakensaldanha.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/arakensaldanha.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/arakensaldanha.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/arakensaldanha.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-1334\" fifu-data-src=\"https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/arakensaldanha.jpg?ssl=1\" alt=\"\" width=\"90\" height=\"103\" \/><\/a><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>M\u00famia<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>Chuck McCann<br \/>\n<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"1\"><b>Araken Saldanha<\/b><em><b><br \/>\n<\/b><\/em><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" colspan=\"3\" align=\"center\" valign=\"top\" width=\"100%\" height=\"1\">\n<hr size=\"1\" \/>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"109\"><a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_mosca.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_mosca.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_mosca.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_mosca.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_mosca.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_mosca.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_mosca.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_mosca.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_mosca.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_mosca.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_mosca.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_mosca.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-2448\" fifu-data-src=\"https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_mosca.jpg?ssl=1\" alt=\"\" width=\"90\" height=\"103\" \/><\/a><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"109\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i1.wp.com\/www.infantv.com.br\/infantv\/dicionario\/donmessik.gif?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i1.wp.com\/www.infantv.com.br\/infantv\/dicionario\/donmessik.gif?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i1.wp.com\/www.infantv.com.br\/infantv\/dicionario\/donmessik.gif?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i1.wp.com\/www.infantv.com.br\/infantv\/dicionario\/donmessik.gif?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i1.wp.com\/www.infantv.com.br\/infantv\/dicionario\/donmessik.gif?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i1.wp.com\/www.infantv.com.br\/infantv\/dicionario\/donmessik.gif?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i1.wp.com\/www.infantv.com.br\/infantv\/dicionario\/donmessik.gif?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i1.wp.com\/www.infantv.com.br\/infantv\/dicionario\/donmessik.gif?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i1.wp.com\/www.infantv.com.br\/infantv\/dicionario\/donmessik.gif?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i1.wp.com\/www.infantv.com.br\/infantv\/dicionario\/donmessik.gif?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i1.wp.com\/www.infantv.com.br\/infantv\/dicionario\/donmessik.gif?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone\" fifu-data-src=\"https:\/\/i1.wp.com\/www.infantv.com.br\/infantv\/dicionario\/donmessik.gif?ssl=1\" alt=\"\" width=\"96\" height=\"110\" \/><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"109\"><a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/mariovilela.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/mariovilela.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/mariovilela.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/mariovilela.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/mariovilela.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/mariovilela.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/mariovilela.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/mariovilela.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/mariovilela.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/mariovilela.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/mariovilela.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/mariovilela.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-2009\" fifu-data-src=\"https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/mariovilela.jpg?ssl=1\" alt=\"\" width=\"90\" height=\"103\" \/><\/a><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>Mosca<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>Don Messick<br \/>\n<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"1\"><b>M\u00e1rio Vilela<\/b><b><\/b><em><b><br \/>\n<\/b><\/em><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>[\/su_tab] [su_tab title=&#8221;Herbert Richers&#8221;]<\/p>\n<table id=\"AutoNumber11\" style=\"border-width: 0;\" border=\"0\" width=\"90%\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" bgcolor=\"#C0C0C0\" width=\"33%\" height=\"1\"><b> PERSONAGEM<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" bgcolor=\"#C0C0C0\" width=\"33%\" height=\"1\"><b> DUBLAGEM<\/b><b> ORIGINAL<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" bgcolor=\"#C0C0C0\" width=\"34%\" height=\"1\"><b> DUBLAGEM<\/b><b> BRASILEIRA<\/b><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"109\"><a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_dracjunior.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_dracjunior.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_dracjunior.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_dracjunior.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_dracjunior.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_dracjunior.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_dracjunior.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_dracjunior.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_dracjunior.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_dracjunior.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_dracjunior.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_dracjunior.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-2443\" fifu-data-src=\"https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_dracjunior.jpg?ssl=1\" alt=\"\" width=\"90\" height=\"103\" \/><\/a><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"109\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i3.wp.com\/infantv.com.br\/infantv\/dicionario\/jerrydexter.gif?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/dicionario\/jerrydexter.gif?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/dicionario\/jerrydexter.gif?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/dicionario\/jerrydexter.gif?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/dicionario\/jerrydexter.gif?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/dicionario\/jerrydexter.gif?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/dicionario\/jerrydexter.gif?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/dicionario\/jerrydexter.gif?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/dicionario\/jerrydexter.gif?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/dicionario\/jerrydexter.gif?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/dicionario\/jerrydexter.gif?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone\" fifu-data-src=\"https:\/\/i3.wp.com\/infantv.com.br\/infantv\/dicionario\/jerrydexter.gif?ssl=1\" alt=\"\" width=\"96\" height=\"110\" \/><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"109\"><a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/claudiogalvan.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/claudiogalvan.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/claudiogalvan.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/claudiogalvan.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/claudiogalvan.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/claudiogalvan.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/claudiogalvan.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/claudiogalvan.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/claudiogalvan.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/claudiogalvan.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/claudiogalvan.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/claudiogalvan.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-2458\" fifu-data-src=\"https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/claudiogalvan.jpg?ssl=1\" alt=\"\" width=\"90\" height=\"103\" \/><\/a><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>Dr\u00e1cula<br \/>\n<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>Jerry Dexter<br \/>\n<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"1\"><b>Cl\u00e1udio Galvan<\/b><em><b><br \/>\n<\/b><\/em><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" colspan=\"3\" align=\"center\" valign=\"top\" width=\"100%\" height=\"1\">\n<hr size=\"1\" \/>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"101\"><a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_lobao.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_lobao.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_lobao.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_lobao.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_lobao.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_lobao.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_lobao.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_lobao.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_lobao.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_lobao.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_lobao.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_lobao.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-2447\" fifu-data-src=\"https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_lobao.jpg?ssl=1\" alt=\"\" width=\"90\" height=\"103\" \/><\/a><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"101\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/williamcallaway.gif?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/williamcallaway.gif?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/williamcallaway.gif?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/williamcallaway.gif?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/williamcallaway.gif?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/williamcallaway.gif?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/williamcallaway.gif?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/williamcallaway.gif?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/williamcallaway.gif?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/williamcallaway.gif?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/williamcallaway.gif?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone\" fifu-data-src=\"https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/williamcallaway.gif?ssl=1\" alt=\"\" width=\"96\" height=\"110\" \/><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"101\"><a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/alexandremoreno.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/alexandremoreno.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/alexandremoreno.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/alexandremoreno.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/alexandremoreno.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/alexandremoreno.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/alexandremoreno.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/alexandremoreno.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/alexandremoreno.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/alexandremoreno.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/alexandremoreno.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/alexandremoreno.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-2460\" fifu-data-src=\"https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/alexandremoreno.jpg?ssl=1\" alt=\"\" width=\"90\" height=\"103\" \/><\/a><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>Lob\u00e3o<br \/>\n<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>William Callaway<br \/>\n<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"1\"><b>Alexandre Moreno<br \/>\n<\/b><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" colspan=\"3\" align=\"center\" valign=\"top\" width=\"100%\" height=\"1\">\n<hr size=\"1\" \/>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"118\"><a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_frankie.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_frankie.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_frankie.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_frankie.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_frankie.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_frankie.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_frankie.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_frankie.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_frankie.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_frankie.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_frankie.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_frankie.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-2445\" fifu-data-src=\"https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_frankie.jpg?ssl=1\" alt=\"\" width=\"90\" height=\"103\" \/><\/a><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"118\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/williamcallaway.gif?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/williamcallaway.gif?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/williamcallaway.gif?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/williamcallaway.gif?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/williamcallaway.gif?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/williamcallaway.gif?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/williamcallaway.gif?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/williamcallaway.gif?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/williamcallaway.gif?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/williamcallaway.gif?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/williamcallaway.gif?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone\" fifu-data-src=\"https:\/\/i0.wp.com\/infantv.com.br\/infantv\/dicionario\/williamcallaway.gif?ssl=1\" alt=\"\" width=\"96\" height=\"110\" \/><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"118\"><a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/luiscarlospersy.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/luiscarlospersy.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/luiscarlospersy.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/luiscarlospersy.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/luiscarlospersy.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/luiscarlospersy.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/luiscarlospersy.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/luiscarlospersy.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/luiscarlospersy.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/luiscarlospersy.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/luiscarlospersy.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/luiscarlospersy.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-2459\" fifu-data-src=\"https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/luiscarlospersy.jpg?ssl=1\" alt=\"\" width=\"90\" height=\"103\" \/><\/a><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>Frankie<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>William Callaway<br \/>\n<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"1\"><b>Lu\u00eds Carlos Persy<\/b><em><b><br \/>\n<\/b><\/em><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" colspan=\"3\" align=\"center\" valign=\"top\" width=\"100%\" height=\"1\">\n<hr size=\"1\" \/>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"109\"><a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_granded.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_granded.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_granded.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_granded.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_granded.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_granded.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_granded.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_granded.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_granded.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_granded.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_granded.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_granded.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-2446\" fifu-data-src=\"https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_granded.jpg?ssl=1\" alt=\"\" width=\"90\" height=\"103\" \/><\/a><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"109\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/alanoppenheimer.gif?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/alanoppenheimer.gif?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/alanoppenheimer.gif?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/alanoppenheimer.gif?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/alanoppenheimer.gif?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/alanoppenheimer.gif?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/alanoppenheimer.gif?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/alanoppenheimer.gif?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/alanoppenheimer.gif?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/alanoppenheimer.gif?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/alanoppenheimer.gif?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone\" fifu-data-src=\"https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/alanoppenheimer.gif?ssl=1\" alt=\"\" width=\"96\" height=\"110\" \/><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"109\"><a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/josesantacruz.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/josesantacruz.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/josesantacruz.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/josesantacruz.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/josesantacruz.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/josesantacruz.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/josesantacruz.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/josesantacruz.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/josesantacruz.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/josesantacruz.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/josesantacruz.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/josesantacruz.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-583\" fifu-data-src=\"https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/06\/josesantacruz.jpg?ssl=1\" alt=\"\" width=\"90\" height=\"103\" \/><\/a><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>Grande D.<br \/>\n<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>Alan Oppenheimer<br \/>\n<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"1\"><b>Jos\u00e9 Santa Cruz<\/b><em><b><br \/>\n<\/b><\/em><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" colspan=\"3\" align=\"center\" valign=\"top\" width=\"100%\" height=\"1\">\n<hr size=\"1\" \/>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"109\"><a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_drterror.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_drterror.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_drterror.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_drterror.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_drterror.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_drterror.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_drterror.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_drterror.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_drterror.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_drterror.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_drterror.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_drterror.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-2444\" fifu-data-src=\"https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_drterror.jpg?ssl=1\" alt=\"\" width=\"90\" height=\"103\" \/><\/a><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"109\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/hansconried.gif?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/hansconried.gif?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/hansconried.gif?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/hansconried.gif?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/hansconried.gif?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/hansconried.gif?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/hansconried.gif?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/hansconried.gif?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/hansconried.gif?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/hansconried.gif?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/hansconried.gif?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone\" fifu-data-src=\"https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/hansconried.gif?ssl=1\" alt=\"\" width=\"96\" height=\"110\" \/><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"109\"><a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/jomerypozzoli.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/jomerypozzoli.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/jomerypozzoli.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/jomerypozzoli.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/jomerypozzoli.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/jomerypozzoli.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/jomerypozzoli.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/jomerypozzoli.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/jomerypozzoli.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/jomerypozzoli.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/jomerypozzoli.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/jomerypozzoli.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-2234\" fifu-data-src=\"https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/jomerypozzoli.jpg?ssl=1\" alt=\"\" width=\"90\" height=\"103\" \/><\/a><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>Dr. Terror<br \/>\n<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>Hans Conried<br \/>\n<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"1\"><b>Jomery Pozzoli<\/b><em><b><br \/>\n<\/b><\/em><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" colspan=\"3\" align=\"center\" valign=\"top\" width=\"100%\" height=\"1\">\n<hr size=\"1\" \/>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"109\"><a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_sapao.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_sapao.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_sapao.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_sapao.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_sapao.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_sapao.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_sapao.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_sapao.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_sapao.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_sapao.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_sapao.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_sapao.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-2450\" fifu-data-src=\"https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_sapao.jpg?ssl=1\" alt=\"\" width=\"90\" height=\"103\" \/><\/a><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"109\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i1.wp.com\/www.infantv.com.br\/infantv\/dicionario\/donmessik.gif?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i1.wp.com\/www.infantv.com.br\/infantv\/dicionario\/donmessik.gif?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i1.wp.com\/www.infantv.com.br\/infantv\/dicionario\/donmessik.gif?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i1.wp.com\/www.infantv.com.br\/infantv\/dicionario\/donmessik.gif?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i1.wp.com\/www.infantv.com.br\/infantv\/dicionario\/donmessik.gif?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i1.wp.com\/www.infantv.com.br\/infantv\/dicionario\/donmessik.gif?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i1.wp.com\/www.infantv.com.br\/infantv\/dicionario\/donmessik.gif?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i1.wp.com\/www.infantv.com.br\/infantv\/dicionario\/donmessik.gif?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i1.wp.com\/www.infantv.com.br\/infantv\/dicionario\/donmessik.gif?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i1.wp.com\/www.infantv.com.br\/infantv\/dicionario\/donmessik.gif?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i1.wp.com\/www.infantv.com.br\/infantv\/dicionario\/donmessik.gif?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone\" fifu-data-src=\"https:\/\/i1.wp.com\/www.infantv.com.br\/infantv\/dicionario\/donmessik.gif?ssl=1\" alt=\"\" width=\"96\" height=\"110\" \/><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"109\"><a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dudaespinoza.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dudaespinoza.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dudaespinoza.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dudaespinoza.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dudaespinoza.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dudaespinoza.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dudaespinoza.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dudaespinoza.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dudaespinoza.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dudaespinoza.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dudaespinoza.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dudaespinoza.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-2461\" fifu-data-src=\"https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dudaespinoza.jpg?ssl=1\" alt=\"\" width=\"90\" height=\"103\" \/><\/a><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>Sap\u00e3o<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>Don Messick<br \/>\n<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"1\"><b>Duda Espinoza<\/b><em><b><br \/>\n<\/b><\/em><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" colspan=\"3\" align=\"center\" valign=\"top\" width=\"100%\" height=\"1\">\n<hr size=\"1\" \/>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"109\"><a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_vampira.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_vampira.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_vampira.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_vampira.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_vampira.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_vampira.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_vampira.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_vampira.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_vampira.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_vampira.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_vampira.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_vampira.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-2451\" fifu-data-src=\"https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_vampira.jpg?ssl=1\" alt=\"\" width=\"90\" height=\"103\" \/><\/a><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"109\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i3.wp.com\/infantv.com.br\/infantv\/dicionario\/juliemac.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/dicionario\/juliemac.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/dicionario\/juliemac.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/dicionario\/juliemac.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/dicionario\/juliemac.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/dicionario\/juliemac.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/dicionario\/juliemac.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/dicionario\/juliemac.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/dicionario\/juliemac.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/dicionario\/juliemac.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/dicionario\/juliemac.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone\" fifu-data-src=\"https:\/\/i3.wp.com\/infantv.com.br\/infantv\/dicionario\/juliemac.jpg?ssl=1\" alt=\"\" width=\"96\" height=\"110\" \/><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"109\"><a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/fernandabaronne.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/fernandabaronne.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/fernandabaronne.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/fernandabaronne.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/fernandabaronne.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/fernandabaronne.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/fernandabaronne.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/fernandabaronne.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/fernandabaronne.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/fernandabaronne.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/fernandabaronne.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/fernandabaronne.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-2462\" fifu-data-src=\"https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/fernandabaronne.jpg?ssl=1\" alt=\"\" width=\"90\" height=\"103\" \/><\/a><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>Vampira<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>Julie McWhirter<br \/>\n<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"1\"><b>Fernanda Baronne<\/b><em><b><br \/>\n<\/b><\/em><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" colspan=\"3\" align=\"center\" valign=\"top\" width=\"100%\" height=\"1\">\n<hr size=\"1\" \/>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"109\"><a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_mumia.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_mumia.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_mumia.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_mumia.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_mumia.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_mumia.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_mumia.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_mumia.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_mumia.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_mumia.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_mumia.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_mumia.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-2449\" fifu-data-src=\"https:\/\/i1.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_mumia.jpg?ssl=1\" alt=\"\" width=\"90\" height=\"103\" \/><\/a><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"109\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/chuckmccann.gif?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/chuckmccann.gif?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/chuckmccann.gif?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/chuckmccann.gif?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/chuckmccann.gif?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/chuckmccann.gif?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/chuckmccann.gif?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/chuckmccann.gif?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/chuckmccann.gif?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/chuckmccann.gif?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/chuckmccann.gif?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone\" fifu-data-src=\"https:\/\/i2.wp.com\/infantv.com.br\/infantv\/dicionario\/chuckmccann.gif?ssl=1\" alt=\"\" width=\"96\" height=\"110\" \/><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"109\"><a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/jorgevasconcellos.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/jorgevasconcellos.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/jorgevasconcellos.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/jorgevasconcellos.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/jorgevasconcellos.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/jorgevasconcellos.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/jorgevasconcellos.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/jorgevasconcellos.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/jorgevasconcellos.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/jorgevasconcellos.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/jorgevasconcellos.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/jorgevasconcellos.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-2463\" fifu-data-src=\"https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/jorgevasconcellos.jpg?ssl=1\" alt=\"\" width=\"90\" height=\"103\" \/><\/a><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>M\u00famia<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>Chuck McCann<br \/>\n<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"1\"><b>Jorge Vasconcellos<\/b><em><b><br \/>\n<\/b><\/em><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" colspan=\"3\" align=\"center\" valign=\"top\" width=\"100%\" height=\"1\">\n<hr size=\"1\" \/>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"109\"><a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_mosca.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_mosca.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_mosca.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_mosca.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_mosca.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_mosca.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_mosca.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_mosca.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_mosca.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_mosca.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_mosca.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_mosca.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-2448\" fifu-data-src=\"https:\/\/i3.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/07\/dracula_mosca.jpg?ssl=1\" alt=\"\" width=\"90\" height=\"103\" \/><\/a><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"109\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i1.wp.com\/www.infantv.com.br\/infantv\/dicionario\/donmessik.gif?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i1.wp.com\/www.infantv.com.br\/infantv\/dicionario\/donmessik.gif?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i1.wp.com\/www.infantv.com.br\/infantv\/dicionario\/donmessik.gif?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i1.wp.com\/www.infantv.com.br\/infantv\/dicionario\/donmessik.gif?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i1.wp.com\/www.infantv.com.br\/infantv\/dicionario\/donmessik.gif?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i1.wp.com\/www.infantv.com.br\/infantv\/dicionario\/donmessik.gif?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i1.wp.com\/www.infantv.com.br\/infantv\/dicionario\/donmessik.gif?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i1.wp.com\/www.infantv.com.br\/infantv\/dicionario\/donmessik.gif?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i1.wp.com\/www.infantv.com.br\/infantv\/dicionario\/donmessik.gif?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i1.wp.com\/www.infantv.com.br\/infantv\/dicionario\/donmessik.gif?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i1.wp.com\/www.infantv.com.br\/infantv\/dicionario\/donmessik.gif?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone\" fifu-data-src=\"https:\/\/i1.wp.com\/www.infantv.com.br\/infantv\/dicionario\/donmessik.gif?ssl=1\" alt=\"\" width=\"96\" height=\"110\" \/><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"109\"><a href=\"http:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/05\/duvida.jpg\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/05\/duvida.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/05\/duvida.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/05\/duvida.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/05\/duvida.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/05\/duvida.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/05\/duvida.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/05\/duvida.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/05\/duvida.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/05\/duvida.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/05\/duvida.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/05\/duvida.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-160\" fifu-data-src=\"https:\/\/i2.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2016\/05\/duvida.jpg?ssl=1\" alt=\"\" width=\"90\" height=\"103\" \/><\/a><\/td>\n<\/tr>\n<tr>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>Mosca<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"33%\" height=\"1\"><b>Don Messick<br \/>\n<\/b><\/td>\n<td style=\"border-style: none; border-width: medium;\" align=\"center\" valign=\"top\" width=\"34%\" height=\"1\"><b><em>Sem Identifica\u00e7\u00e3o<\/em><\/b><em><b><br \/>\n<\/b><\/em><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>[\/su_tab][\/su_tabs]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Est\u00fadio de dublagem: \u00c1lamo Est\u00fadio de redublagem:\u00a0 Herbert Richers [su_tabs][su_tab title=&#8221;\u00c1lamo&#8221;] PERSONAGEM DUBLAGEM ORIGINAL DUBLAGEM BRASILEIRA \u00a0 Drac J\u00fanior Jerry Dexter Renato M\u00e1rcio Lob\u00e3o William Callaway Nelson Machado Frankie William Callaway Jos\u00e9 Carlos Guerra Dracul\u00e3o Alan Oppenheimer Gast\u00e3o Malta Dr. Terror Hans Conried M\u00e1rio Jorge Montini Sap\u00e3o Don Messick Mauro de Almeida Vampira Julie McWhirter [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2443,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","fifu_image_url":"","fifu_image_alt":""},"categories":[20],"tags":[],"_links":{"self":[{"href":"https:\/\/infantv.com.br\/infantv\/wp-json\/wp\/v2\/posts\/2442"}],"collection":[{"href":"https:\/\/infantv.com.br\/infantv\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infantv.com.br\/infantv\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infantv.com.br\/infantv\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/infantv.com.br\/infantv\/wp-json\/wp\/v2\/comments?post=2442"}],"version-history":[{"count":4,"href":"https:\/\/infantv.com.br\/infantv\/wp-json\/wp\/v2\/posts\/2442\/revisions"}],"predecessor-version":[{"id":2457,"href":"https:\/\/infantv.com.br\/infantv\/wp-json\/wp\/v2\/posts\/2442\/revisions\/2457"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infantv.com.br\/infantv\/wp-json\/wp\/v2\/media\/2443"}],"wp:attachment":[{"href":"https:\/\/infantv.com.br\/infantv\/wp-json\/wp\/v2\/media?parent=2442"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infantv.com.br\/infantv\/wp-json\/wp\/v2\/categories?post=2442"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infantv.com.br\/infantv\/wp-json\/wp\/v2\/tags?post=2442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}