{"id":19000,"date":"2017-01-23T19:17:18","date_gmt":"2017-01-23T19:17:18","guid":{"rendered":"http:\/\/www.infantv.com.br\/infantv\/?p=19000"},"modified":"2017-01-23T19:17:43","modified_gmt":"2017-01-23T19:17:43","slug":"vamp-1991-elenco","status":"publish","type":"post","link":"https:\/\/infantv.com.br\/infantv\/vamp-1991-elenco\/","title":{"rendered":"Vamp (1991) &#8211; Elenco"},"content":{"rendered":"<div style=\"text-align:center\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2017\/01\/vamp6.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2017\/01\/vamp6.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2017\/01\/vamp6.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2017\/01\/vamp6.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2017\/01\/vamp6.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2017\/01\/vamp6.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2017\/01\/vamp6.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2017\/01\/vamp6.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2017\/01\/vamp6.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2017\/01\/vamp6.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2017\/01\/vamp6.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" width=\"400\" height=\"299\" fifu-data-src=\"https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2017\/01\/vamp6.jpg?ssl=1\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Vamp (1991) \u2013 Elenco\" title=\"Vamp (1991) \u2013 Elenco\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/i0.wp.com\/infantv.com.br\/infantv\/wp-content\/uploads\/2017\/01\/vamp6.jpg?ssl=1 400w, https:\/\/infantv.com.br\/infantv\/wp-content\/uploads\/2017\/01\/vamp6-300x224.jpg 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/div><p style=\"text-align: center;\"><a href=\"http:\/\/www.infantv.com.br\/infantv\/?p=18977\"><img src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i3.wp.com\/www.infantv.com.br\/infantv\/wp-content\/uploads\/2017\/01\/vamp.jpg?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i3.wp.com\/www.infantv.com.br\/infantv\/wp-content\/uploads\/2017\/01\/vamp.jpg?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i3.wp.com\/www.infantv.com.br\/infantv\/wp-content\/uploads\/2017\/01\/vamp.jpg?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i3.wp.com\/www.infantv.com.br\/infantv\/wp-content\/uploads\/2017\/01\/vamp.jpg?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i3.wp.com\/www.infantv.com.br\/infantv\/wp-content\/uploads\/2017\/01\/vamp.jpg?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i3.wp.com\/www.infantv.com.br\/infantv\/wp-content\/uploads\/2017\/01\/vamp.jpg?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i3.wp.com\/www.infantv.com.br\/infantv\/wp-content\/uploads\/2017\/01\/vamp.jpg?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i3.wp.com\/www.infantv.com.br\/infantv\/wp-content\/uploads\/2017\/01\/vamp.jpg?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i3.wp.com\/www.infantv.com.br\/infantv\/wp-content\/uploads\/2017\/01\/vamp.jpg?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i3.wp.com\/www.infantv.com.br\/infantv\/wp-content\/uploads\/2017\/01\/vamp.jpg?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i3.wp.com\/www.infantv.com.br\/infantv\/wp-content\/uploads\/2017\/01\/vamp.jpg?ssl=1&w=1600&resize=1600&ssl=1 1600w\" decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-18987 size-full\" style=\"border-radius: 20px;\" fifu-data-src=\"https:\/\/i3.wp.com\/www.infantv.com.br\/infantv\/wp-content\/uploads\/2017\/01\/vamp.jpg?ssl=1\" alt=\"\" width=\"300\" height=\"229\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Ney Latorraca &#8211; Vlad<\/p>\n<p style=\"text-align: center;\">Cl\u00e1udia Ohana &#8211; Natasha e Eug\u00eania<\/p>\n<p style=\"text-align: center;\">Reginaldo Faria &#8211; Capit\u00e3o Jonas Rocha<\/p>\n<p style=\"text-align: center;\">Joana Fomm &#8211; Carmem Maura<\/p>\n<p style=\"text-align: center;\">F\u00e1bio Assun\u00e7\u00e3o &#8211; Lippi<\/p>\n<p style=\"text-align: center;\">Nuno Leal Maia &#8211; Jurandir<\/p>\n<p style=\"text-align: center;\">Patr\u00edcia Travassos &#8211; Mary Matoso<\/p>\n<p style=\"text-align: center;\">Ot\u00e1vio Augusto &#8211; Matoso<\/p>\n<p style=\"text-align: center;\">Guilherme Leme &#8211; Gerald<\/p>\n<p style=\"text-align: center;\">Paulo Gracindo &#8211; Cachorr\u00e3o<\/p>\n<p style=\"text-align: center;\">Vera Holtz &#8211; Alice Penn Taylor<\/p>\n<p style=\"text-align: center;\">Marcos Frota &#8211; Augusto S\u00e9rgio<\/p>\n<p style=\"text-align: center;\">Evandro Mesquita &#8211; Sim\u00e3o<\/p>\n<p style=\"text-align: center;\">Beth Coelho &#8211; Jezebel<\/p>\n<p style=\"text-align: center;\">Marcos Breda &#8211; Rafa e Diogo<\/p>\n<p style=\"text-align: center;\">Igor Lage &#8211; Pingo<\/p>\n<p style=\"text-align: center;\">Daniela Camargo &#8211; Lena<\/p>\n<p style=\"text-align: center;\">Bel Kutner &#8211; Scarleth<\/p>\n<p style=\"text-align: center;\">Carol Machado &#8211; Dorothy<\/p>\n<p style=\"text-align: center;\">Henrique Farias &#8211; Nando<\/p>\n<p style=\"text-align: center;\">Jonas Torres &#8211; Daniel<\/p>\n<p style=\"text-align: center;\">Luciana Vendraminni &#8211; Jade<\/p>\n<p style=\"text-align: center;\">Rodrigo Penna &#8211; Le\u00f3n<\/p>\n<p style=\"text-align: center;\">Jo\u00e3o Rebello &#8211; Sig<\/p>\n<p style=\"text-align: center;\">Fernanda Rodrigues &#8211; Isa<\/p>\n<p style=\"text-align: center;\">Jos\u00e9 Paulo Jr. &#8211; Tico<\/p>\n<p style=\"text-align: center;\">Pedro Vasconcellos &#8211; Jo\u00e3o<\/p>\n<p style=\"text-align: center;\">Juliana Martins &#8211; Esmeralda<\/p>\n<p style=\"text-align: center;\">Frederico Mayrinck &#8211; Pedro<\/p>\n<p style=\"text-align: center;\">Amora Mautner &#8211; Paula<\/p>\n<p style=\"text-align: center;\">Aleph Del Moral &#8211; Rubinho<\/p>\n<p style=\"text-align: center;\">Andr\u00e9 Gon\u00e7alves &#8211; Matosinho<\/p>\n<p style=\"text-align: center;\">Fl\u00e1vio Silvino &#8211; Matos\u00e3o<\/p>\n<p style=\"text-align: center;\">Cleyde Y\u00e1conis &#8211; Virg\u00ednia<\/p>\n<p style=\"text-align: center;\">Bia Seidl &#8211; Soninha<\/p>\n<p style=\"text-align: center;\">Vera Zimermann &#8211; Marina<\/p>\n<p style=\"text-align: center;\">Francisco Milani &#8211; Max<\/p>\n<p style=\"text-align: center;\">Tony Tornado &#8211; Pai Gil<\/p>\n<p style=\"text-align: center;\">A\u00edda Leinner &#8211; Branca<\/p>\n<p style=\"text-align: center;\">Paulo Jos\u00e9 &#8211; Ivan<\/p>\n<p style=\"text-align: center;\">Zez\u00e9 Polessa &#8211; S\u00edlvia<\/p>\n<p style=\"text-align: center;\">Oswaldo Louzada &#8211; Padre Eus\u00e9bio<\/p>\n<p style=\"text-align: center;\">Marcos Alvisi &#8211; Padre Est\u00eav\u00e3o<\/p>\n<p style=\"text-align: center;\">In\u00eas Galv\u00e3o &#8211; Joana<\/p>\n<p style=\"text-align: center;\">Marcelo Picchi &#8211; Moreira<\/p>\n<p style=\"text-align: center;\">Norma Geraldy &#8211; Hemengharda<\/p>\n<p style=\"text-align: center;\">Hilda Rebello &#8211; Herm\u00ednia<\/p>\n<p style=\"text-align: center;\">Jorge Cherques &#8211; Frei Bartolomeu<\/p>\n<p style=\"text-align: center;\">Eduardo Machado &#8211; Frei Ambr\u00f3sio<\/p>\n<p style=\"text-align: center;\">Rejane Schumann &#8211; Maria Carmem<\/p>\n<p style=\"text-align: center;\">Waldemar Berditchewsky<\/p>\n<p style=\"text-align: center;\">Ernani Moraes &#8211; Barros<\/p>\n<p style=\"text-align: center;\">Felipe Pinheiro &#8211; Giron<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ney Latorraca &#8211; Vlad Cl\u00e1udia Ohana &#8211; Natasha e Eug\u00eania Reginaldo Faria &#8211; Capit\u00e3o Jonas Rocha Joana Fomm &#8211; Carmem Maura F\u00e1bio Assun\u00e7\u00e3o &#8211; Lippi Nuno Leal Maia &#8211; Jurandir Patr\u00edcia Travassos &#8211; Mary Matoso Ot\u00e1vio Augusto &#8211; Matoso Guilherme Leme &#8211; Gerald Paulo Gracindo &#8211; Cachorr\u00e3o Vera Holtz &#8211; Alice Penn Taylor Marcos Frota [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":18979,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","fifu_image_url":"","fifu_image_alt":""},"categories":[20],"tags":[],"_links":{"self":[{"href":"https:\/\/infantv.com.br\/infantv\/wp-json\/wp\/v2\/posts\/19000"}],"collection":[{"href":"https:\/\/infantv.com.br\/infantv\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infantv.com.br\/infantv\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infantv.com.br\/infantv\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/infantv.com.br\/infantv\/wp-json\/wp\/v2\/comments?post=19000"}],"version-history":[{"count":2,"href":"https:\/\/infantv.com.br\/infantv\/wp-json\/wp\/v2\/posts\/19000\/revisions"}],"predecessor-version":[{"id":19003,"href":"https:\/\/infantv.com.br\/infantv\/wp-json\/wp\/v2\/posts\/19000\/revisions\/19003"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infantv.com.br\/infantv\/wp-json\/wp\/v2\/media\/18979"}],"wp:attachment":[{"href":"https:\/\/infantv.com.br\/infantv\/wp-json\/wp\/v2\/media?parent=19000"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infantv.com.br\/infantv\/wp-json\/wp\/v2\/categories?post=19000"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infantv.com.br\/infantv\/wp-json\/wp\/v2\/tags?post=19000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}